{"id":4219,"date":"2023-03-27T17:52:46","date_gmt":"2023-03-27T17:52:46","guid":{"rendered":"https:\/\/april-belgium.be\/?post_type=blog_news&#038;p=4219"},"modified":"2023-03-27T17:52:46","modified_gmt":"2023-03-27T17:52:46","slug":"assurance-deces-sujet-mort","status":"publish","type":"blog_news","link":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/","title":{"rendered":"La mort, un sujet si sensible \u00e0 aborder&#8230;"},"content":{"rendered":"<p>Vendre une assurance d\u00e9c\u00e8s, c&rsquo;est forc\u00e9ment aborder le sujet d\u00e9licat de la mort. Un sujet qui semble tabou, mais qui pourtant nous concerne tous. Nous vous aidons \u00e0 aborder ce sujet avec vos clients. Voici quelques conseils pour parler de la mort sous un autre angle. D\u00e9couvrez notre infographie.\u00a0<\/p>\n<p><a href=\"https:\/\/april-belgium.be\/wp-content\/uploads\/INFOGRAPHIE_lever-les-tabous-FR.pdf\" target=\"_blank\" rel=\"noopener\">INFOGRAPHIE_lever les tabous FR<\/a><\/p>\n","protected":false},"featured_media":4229,"template":"","categories":[39,40],"class_list":["post-4219","blog_news","type-blog_news","status-publish","has-post-thumbnail","hentry","category-blog","category-protection-de-la-famille"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>La mort, un sujet si sensible \u00e0 aborder... - APRIL Belgium<\/title>\n<meta name=\"description\" content=\"D\u00e9couvrez notre infographie qui vous donnera quelques pistes pour aborder le sujet du d\u00e9c\u00e8s avec vos clients.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La mort, un sujet si sensible \u00e0 aborder... - APRIL Belgium\" \/>\n<meta property=\"og:description\" content=\"D\u00e9couvrez notre infographie qui vous donnera quelques pistes pour aborder le sujet du d\u00e9c\u00e8s avec vos clients.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/\" \/>\n<meta property=\"og:site_name\" content=\"APRIL Belgium\" \/>\n<meta property=\"og:image\" content=\"https:\/\/april-belgium.be\/wp-content\/uploads\/Tristesse.webp\" \/>\n\t<meta property=\"og:image:width\" content=\"1073\" \/>\n\t<meta property=\"og:image:height\" content=\"750\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/webp\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/blog_news\\\/assurance-deces-sujet-mort\\\/\",\"url\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/blog_news\\\/assurance-deces-sujet-mort\\\/\",\"name\":\"La mort, un sujet si sensible \u00e0 aborder... - APRIL Belgium\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/blog_news\\\/assurance-deces-sujet-mort\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/blog_news\\\/assurance-deces-sujet-mort\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/april-belgium.be\\\/wp-content\\\/uploads\\\/Tristesse.webp\",\"datePublished\":\"2023-03-27T17:52:46+00:00\",\"description\":\"D\u00e9couvrez notre infographie qui vous donnera quelques pistes pour aborder le sujet du d\u00e9c\u00e8s avec vos clients.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/blog_news\\\/assurance-deces-sujet-mort\\\/#breadcrumb\"},\"inLanguage\":\"fr-BE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/april-belgium.be\\\/fr\\\/blog_news\\\/assurance-deces-sujet-mort\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-BE\",\"@id\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/blog_news\\\/assurance-deces-sujet-mort\\\/#primaryimage\",\"url\":\"https:\\\/\\\/april-belgium.be\\\/wp-content\\\/uploads\\\/Tristesse.webp\",\"contentUrl\":\"https:\\\/\\\/april-belgium.be\\\/wp-content\\\/uploads\\\/Tristesse.webp\",\"width\":1073,\"height\":750},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/blog_news\\\/assurance-deces-sujet-mort\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La mort, un sujet si sensible \u00e0 aborder&#8230;\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/#website\",\"url\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/\",\"name\":\"APRIL Belgium\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/april-belgium.be\\\/fr\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-BE\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La mort, un sujet si sensible \u00e0 aborder... - APRIL Belgium","description":"D\u00e9couvrez notre infographie qui vous donnera quelques pistes pour aborder le sujet du d\u00e9c\u00e8s avec vos clients.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/","og_locale":"fr_FR","og_type":"article","og_title":"La mort, un sujet si sensible \u00e0 aborder... - APRIL Belgium","og_description":"D\u00e9couvrez notre infographie qui vous donnera quelques pistes pour aborder le sujet du d\u00e9c\u00e8s avec vos clients.","og_url":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/","og_site_name":"APRIL Belgium","og_image":[{"width":1073,"height":750,"url":"https:\/\/april-belgium.be\/wp-content\/uploads\/Tristesse.webp","type":"image\/webp"}],"twitter_card":"summary_large_image","twitter_misc":{"Dur\u00e9e de lecture est.":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/","url":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/","name":"La mort, un sujet si sensible \u00e0 aborder... - APRIL Belgium","isPartOf":{"@id":"https:\/\/april-belgium.be\/fr\/#website"},"primaryImageOfPage":{"@id":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/#primaryimage"},"image":{"@id":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/#primaryimage"},"thumbnailUrl":"https:\/\/april-belgium.be\/wp-content\/uploads\/Tristesse.webp","datePublished":"2023-03-27T17:52:46+00:00","description":"D\u00e9couvrez notre infographie qui vous donnera quelques pistes pour aborder le sujet du d\u00e9c\u00e8s avec vos clients.","breadcrumb":{"@id":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/#breadcrumb"},"inLanguage":"fr-BE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/"]}]},{"@type":"ImageObject","inLanguage":"fr-BE","@id":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/#primaryimage","url":"https:\/\/april-belgium.be\/wp-content\/uploads\/Tristesse.webp","contentUrl":"https:\/\/april-belgium.be\/wp-content\/uploads\/Tristesse.webp","width":1073,"height":750},{"@type":"BreadcrumbList","@id":"https:\/\/april-belgium.be\/fr\/blog_news\/assurance-deces-sujet-mort\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/april-belgium.be\/fr\/"},{"@type":"ListItem","position":2,"name":"La mort, un sujet si sensible \u00e0 aborder&#8230;"}]},{"@type":"WebSite","@id":"https:\/\/april-belgium.be\/fr\/#website","url":"https:\/\/april-belgium.be\/fr\/","name":"APRIL Belgium","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/april-belgium.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-BE"}]}},"_links":{"self":[{"href":"https:\/\/april-belgium.be\/fr\/wp-json\/wp\/v2\/blog_news\/4219","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/april-belgium.be\/fr\/wp-json\/wp\/v2\/blog_news"}],"about":[{"href":"https:\/\/april-belgium.be\/fr\/wp-json\/wp\/v2\/types\/blog_news"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/april-belgium.be\/fr\/wp-json\/wp\/v2\/media\/4229"}],"wp:attachment":[{"href":"https:\/\/april-belgium.be\/fr\/wp-json\/wp\/v2\/media?parent=4219"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/april-belgium.be\/fr\/wp-json\/wp\/v2\/categories?post=4219"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}